{"id":1149,"date":"2023-09-06T17:54:21","date_gmt":"2023-09-06T15:54:21","guid":{"rendered":"https:\/\/cyndiemedeiros.com\/?page_id=1149"},"modified":"2026-04-20T10:22:08","modified_gmt":"2026-04-20T08:22:08","slug":"demande-en-mariage","status":"publish","type":"page","link":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/","title":{"rendered":"Demande en mariage"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-d87e38c7203a9ff14d12203087026a99\"><strong>Vous avez pr\u00e9vu de faire votre demande en mariage tr\u00e8s bient\u00f4t et souhaitez immortaliser ce moment unique ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Je capture chaque \u00e9motion de votre demande en mariage avec discr\u00e9tion, sans \u00e9veiller le moindre soup\u00e7on chez votre moiti\u00e9. \u00c0 Paris, chaque lieu devient un d\u00e9cor magique : au pied de la Tour Eiffel, pr\u00e8s de la Pyramide du Louvre, dans un parc, sur le Pont des Arts ou \u00e0 Montmartre\u2026 les possibilit\u00e9s sont infinies.<\/p>\n\n\n\n<p>J\u2019immortalise cet instant unique sur le vif, dans un style naturel et spontan\u00e9, puis je vous rejoins pour une s\u00e9ance photo en amoureux afin de prolonger la magie de ce moment.<\/p>\n\n\n\n<p>Laissez-vous guider et choisissez un lieu qui vous ressemble, charg\u00e9 de sens et d\u2019\u00e9motion, pour une demande en mariage inoubliable.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-1024x1024.jpg\" alt=\"Photographe demande en mariage fian\u00e7aille paris tour eiffel\" class=\"wp-image-3363\" srcset=\"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-1024x1024.jpg 1024w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-300x300.jpg 300w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-150x150.jpg 150w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-768x768.jpg 768w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-75x75.jpg 75w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/cyndiemedeiros.com\/index.php\/devis-contact\/\">R\u00e9servez d\u00e8s maintenant votre shooting photo !<\/a><\/strong><\/p>\n\n\n\n<div class=\"wp-block-cover\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" class=\"wp-block-cover__image-background wp-image-1948\" alt=\"\" src=\"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2024\/06\/Demande-en-mariage_Paris-1-819x1024.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2024\/06\/Demande-en-mariage_Paris-1-819x1024.jpg 819w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2024\/06\/Demande-en-mariage_Paris-1-240x300.jpg 240w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2024\/06\/Demande-en-mariage_Paris-1-768x960.jpg 768w, https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2024\/06\/Demande-en-mariage_Paris-1.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><a href=\"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage-2\/\">Demande en mariage sur Paris<\/a><\/p>\n<\/div><\/div>\n\n\n\n<p><strong>Conditions G\u00e9n\u00e9rales de Vente<\/strong><\/p>\n\n\n\n<p>Toutes les photos r\u00e9ussies seront envoy\u00e9es au format num\u00e9rique HD en JPEG, avec retouche l\u00e9g\u00e8re (colorim\u00e9trie, luminosit\u00e9&#8230;). Minimum 20 photos HD.<\/p>\n\n\n\n<p>Le d\u00e9placement est inclus dans tout Paris intramuros et dans un rayon de 15kms autour de mon domicile sur Charenton (94). Au-del\u00e0, des frais s\u2019appliquent selon le bar\u00e8me kilom\u00e9trique de l\u2019URSSAF : 0,665 \u20ac \/ km<\/p>\n\n\n\n<p>Les \u00e9ventuels frais de stationnement ou de p\u00e9age, trains sp\u00e9ciaux, frais de logement si n\u00e9cessaire, etc. sont refactur\u00e9s en frais r\u00e9els en suppl\u00e9ment.<\/p>\n\n\n\n<p>Un acompte de 30% est demand\u00e9 pour toute r\u00e9servation de date. Le solde est d\u00fb au maximum le jour J et avant l&rsquo;envoi des photos. <\/p>\n\n\n\n<p>En cas de d\u00e9passement des horaires (au-del\u00e0 de 15 minutes) par rapport au devis initial, et sous r\u00e9serve de disponibilit\u00e9 de la photographe, il sera factur\u00e9 au client 60\u20ac par demi-heure entam\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez pr\u00e9vu de faire votre demande en mariage tr\u00e8s bient\u00f4t et souhaitez immortaliser ce moment unique ? Je capture chaque \u00e9motion de votre demande en mariage avec discr\u00e9tion, sans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1149","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demande en mariage - Cyndie Medeiros<\/title>\n<meta name=\"description\" content=\"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demande en mariage - Cyndie Medeiros\" \/>\n<meta property=\"og:description\" content=\"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/\" \/>\n<meta property=\"og:site_name\" content=\"Cyndie Medeiros\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T08:22:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/\",\"url\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/\",\"name\":\"Demande en mariage - Cyndie Medeiros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyndiemedeiros.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Demande-en-mariage-Photo-1024x1024.jpg\",\"datePublished\":\"2023-09-06T15:54:21+00:00\",\"dateModified\":\"2026-04-20T08:22:08+00:00\",\"description\":\"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyndiemedeiros.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Demande-en-mariage-Photo.jpg\",\"contentUrl\":\"https:\\\/\\\/cyndiemedeiros.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Demande-en-mariage-Photo.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/index.php\\\/demande-en-mariage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cyndiemedeiros.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demande en mariage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyndiemedeiros.com\\\/#website\",\"url\":\"https:\\\/\\\/cyndiemedeiros.com\\\/\",\"name\":\"Cyndie Medeiros\",\"description\":\"Photographe Paris &amp; Val-de-Marne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyndiemedeiros.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demande en mariage - Cyndie Medeiros","description":"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/","og_locale":"fr_FR","og_type":"article","og_title":"Demande en mariage - Cyndie Medeiros","og_description":"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.","og_url":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/","og_site_name":"Cyndie Medeiros","article_modified_time":"2026-04-20T08:22:08+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/","url":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/","name":"Demande en mariage - Cyndie Medeiros","isPartOf":{"@id":"https:\/\/cyndiemedeiros.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/#primaryimage"},"image":{"@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/#primaryimage"},"thumbnailUrl":"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo-1024x1024.jpg","datePublished":"2023-09-06T15:54:21+00:00","dateModified":"2026-04-20T08:22:08+00:00","description":"Immortalisez votre demande en mariage \u00e0 Paris avec des photos naturelles, discr\u00e8tes et pleines d\u2019\u00e9motion dans un cadre magique.","breadcrumb":{"@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/#primaryimage","url":"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo.jpg","contentUrl":"https:\/\/cyndiemedeiros.com\/wp-content\/uploads\/2025\/12\/Demande-en-mariage-Photo.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/cyndiemedeiros.com\/index.php\/demande-en-mariage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cyndiemedeiros.com\/"},{"@type":"ListItem","position":2,"name":"Demande en mariage"}]},{"@type":"WebSite","@id":"https:\/\/cyndiemedeiros.com\/#website","url":"https:\/\/cyndiemedeiros.com\/","name":"Cyndie Medeiros","description":"Photographe Paris &amp; Val-de-Marne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyndiemedeiros.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/pages\/1149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/comments?post=1149"}],"version-history":[{"count":30,"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/pages\/1149\/revisions"}],"predecessor-version":[{"id":4015,"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/pages\/1149\/revisions\/4015"}],"wp:attachment":[{"href":"https:\/\/cyndiemedeiros.com\/index.php\/wp-json\/wp\/v2\/media?parent=1149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}